{"id":3420,"date":"2021-06-05T06:28:06","date_gmt":"2021-06-05T06:28:06","guid":{"rendered":"https:\/\/solidscontrolworld.com\/?page_id=3420"},"modified":"2024-10-25T06:04:01","modified_gmt":"2024-10-25T06:04:01","slug":"agitador-de-esquisto","status":"publish","type":"page","link":"https:\/\/solidscontrolworld.com\/es\/shale-shaker\/","title":{"rendered":"Agitador de esquisto"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3420\" class=\"elementor elementor-3420\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7379c9b elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"7379c9b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8b98dd\" data-id=\"b8b98dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70c022aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70c022aa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1b6dff43\" data-id=\"1b6dff43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-549e102 elementor-widget elementor-widget-image\" data-id=\"549e102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"450\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6.jpg\" class=\"attachment-full size-full wp-image-9557\" alt=\"Proveedor de agitadores de lutitas para fluidos de perforaci\u00f3n\" srcset=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6.jpg 700w, https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6-300x193.jpg 300w, https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6-600x386.jpg 600w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380d90d2 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"380d90d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"\u0639\u0627\u0631\u0636 \u0627\u0644\u0635\u0648\u0631\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 \u0645\u0646 3\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"380d90d2\" data-elementor-lightbox-title=\"shale shaker\u7684\u526f\u672c\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAzNjUsInVybCI6Imh0dHBzOlwvXC9zb2xpZHNjb250cm9sd29ybGQuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMlwvc2hhbGUtc2hha2VyXHU3Njg0XHU1MjZmXHU2NzJjLnBuZyIsInNsaWRlc2hvdyI6IjM4MGQ5MGQyIn0%3D\" href=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/02\/shale-shaker\u7684\u526f\u672c.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/02\/shale-shaker\u7684\u526f\u672c-150x150.png\" alt=\"agitador de esquisto\u7684\u526f\u672c\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 \u0645\u0646 3\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"380d90d2\" data-elementor-lightbox-title=\"WechatIMG112\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAzNjYsInVybCI6Imh0dHBzOlwvXC9zb2xpZHNjb250cm9sd29ybGQuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMlwvV2VjaGF0SU1HMTEyLnBuZyIsInNsaWRlc2hvdyI6IjM4MGQ5MGQyIn0%3D\" href=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/02\/WechatIMG112.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/02\/WechatIMG112-150x150.png\" alt=\"WechatIMG112\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 \u0645\u0646 3\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"380d90d2\" data-elementor-lightbox-title=\"WechatIMG111\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTAzNjcsInVybCI6Imh0dHBzOlwvXC9zb2xpZHNjb250cm9sd29ybGQuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wMlwvV2VjaGF0SU1HMTExLnBuZyIsInNsaWRlc2hvdyI6IjM4MGQ5MGQyIn0%3D\" href=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/02\/WechatIMG111.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/02\/WechatIMG111-150x150.png\" alt=\"WechatIMG111\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-71d16ade\" data-id=\"71d16ade\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a577f3 elementor-widget elementor-widget-heading\" data-id=\"7a577f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Agitador de esquisto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-050bec9 elementor-widget elementor-widget-text-editor\" data-id=\"050bec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El fluido de perforaci\u00f3n para zaranda vibratoria es el m\u00e1s utilizado <a href=\"https:\/\/solidscontrolworld.com\/es\/equipo-de-remediacion-de-suelos\/\">equipo de control de s\u00f3lidos<\/a> en el proceso de tratamiento de lodos de perforaci\u00f3n petrolera.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1168183 elementor-widget elementor-widget-text-editor\" data-id=\"1168183\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCategor\u00eda:\u00a0<a href=\"https:\/\/solidscontrolworld.com\/es\/equipos-de-control-de-solidos\/\" rel=\"tag\">Control de s\u00f3lidos<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0fbbbf8\" data-id=\"0fbbbf8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d4e18e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6d4e18e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope-open\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@solidscontrolworld.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-volume\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+8613784677772<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-fax\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">86-315-7651760<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d318f88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d318f88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-edfc814\" data-id=\"edfc814\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d051d4 elementor-widget elementor-widget-heading\" data-id=\"0d051d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Definici\u00f3n de fluido de perforaci\u00f3n para zaranda vibratoria<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f116279 elementor-widget elementor-widget-text-editor\" data-id=\"f116279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El agitador de lodos para fluidos de perforaci\u00f3n es el equipo de control de s\u00f3lidos m\u00e1s utilizado en el tratamiento de lodos de perforaci\u00f3n petrolera. Por lo tanto, el agitador de lodos seleccionado debe ofrecer ventajas como alta resistencia a la vibraci\u00f3n, amplia \u00e1rea de cribado, \u00e1ngulo ajustable de la caja de cribado y estructura compacta. El agitador de lodos para fluidos de perforaci\u00f3n desempe\u00f1a un papel decisivo en todo el sistema de reciclaje de purificaci\u00f3n de lodos. Actualmente, se utiliza ampliamente en la perforaci\u00f3n petrolera, el cruce direccional horizontal sin excavaci\u00f3n, la perforaci\u00f3n de metano en yacimientos de carb\u00f3n, la perforaci\u00f3n de gas de esquisto, la protecci\u00f3n ambiental de lodos fluviales y otras aplicaciones. <a href=\"https:\/\/solidscontrolworld.com\/es\/desarenador\/\"><strong>tratamiento de purificaci\u00f3n de lodos<\/strong><\/a> campos.<br \/>Es el equipo clave en el<span style=\"color: #008000;\">\u00a0<a style=\"color: #008000;\" href=\"https:\/\/solidscontrolworld.com\/es\/our-products-2\/\" target=\"_blank\" rel=\"noopener\">equipo de control de s\u00f3lidos<\/a>,<\/span> Este equipo se encarga de limpiar una gran cantidad de recortes de perforaci\u00f3n, controlar el contenido de s\u00f3lidos, reducir la carga de trabajo del equipo de control de s\u00f3lidos de nivel inferior y suministrar fluido de perforaci\u00f3n a dicho equipo para cumplir con los requisitos de tratamiento. El proceso de perforaci\u00f3n requiere que la zaranda vibratoria de fluido de perforaci\u00f3n elimine la mayor cantidad posible de s\u00f3lidos da\u00f1inos y recupere la mayor cantidad posible de fluido de perforaci\u00f3n. Si la zaranda vibratoria falla, el siguiente nivel del equipo de control de s\u00f3lidos se sobrecargar\u00e1 o incluso no podr\u00e1 funcionar con normalidad, lo que resultar\u00e1 en un contenido excesivo de s\u00f3lidos en el... <span title=\"Proveedor de agitadores de lutitas para fluidos de perforaci\u00f3n\">fluido de perforaci\u00f3n,<\/span> haciendo el <a title=\"Proveedor de agitadores de lutitas para fluidos de perforaci\u00f3n\">fluido de perforaci\u00f3n<\/a> El rendimiento se ha deteriorado, lo que afecta gravemente la seguridad y la velocidad de la perforaci\u00f3n. Para mejorar el rendimiento del zarandeador de lutitas con fluido de perforaci\u00f3n, se ha desarrollado una estructura que ha pasado de ser un zarandeador de lutitas de inercia de un solo eje y un zarandeador de lutitas de inercia de doble eje a un zarandeador de lutitas inteligente de bajo consumo. La estructura del zarandeador ha evolucionado desde una malla de una sola capa, una malla de una sola capa con borde en forma de gancho, una malla plana de doble capa con borde en forma de gancho y una malla c\u00f3nica corrugada hasta la malla multicapa de marco compuesto, con una malla de malla baja a alta.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a0eb42 elementor-widget elementor-widget-heading\" data-id=\"0a0eb42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Composici\u00f3n y agitador de lutitas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebfdaa2 elementor-widget elementor-widget-text-editor\" data-id=\"ebfdaa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tFluido de perforaci\u00f3n <a href=\"https:\/\/solidscontrolworld.com\/es\/reemplazo-de-pantalla-vibratoria-para-zaranda-vibratoria-de-pizarra-derrick\/\"><strong>agitador de esquisto<\/strong><\/a> Se compone principalmente de base, caja de pantalla, <a href=\"https:\/\/solidscontrolworld.com\/es\/reemplazo-de-pantalla-vibratoria-para-zaranda-vibratoria-de-pizarra-derrick\/\"><strong>pantallas vibratorias<\/strong><\/a>, <a href=\"https:\/\/solidscontrolworld.com\/es\/limpiador-de-lodo\/\">lodo<\/a> Caja de alimentaci\u00f3n, motor vibratorio, resorte amortiguador de vibraciones, interruptor de control y otras piezas. La base se utiliza para fijar los tornillos a la cimentaci\u00f3n; los soportes (soporte y soporte del motor) sirven para sostener la caja de cribado y el motor; el resorte de soporte genera la amplitud, y el motor vibratorio (excitador) es el componente m\u00e1s importante de la zaranda vibratoria, ya que es la fuente de energ\u00eda de la zaranda vibratoria y permite que esta alcance la amplitud de vibraci\u00f3n requerida. La estructura de los componentes principales es la siguiente:\n\n<img decoding=\"async\" class=\"alignleft wp-image-7310 size-full\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2022\/05\/8d7fde11d3c4253bf74861dc915b59a.jpg\" alt=\"Proveedor de agitadores de lutitas para fluidos de perforaci\u00f3n\" title=\"Proveedor de agitadores de lutitas para fluidos de perforaci\u00f3n\" width=\"474\" height=\"216\" srcset=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2022\/05\/8d7fde11d3c4253bf74861dc915b59a.jpg 474w, https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2022\/05\/8d7fde11d3c4253bf74861dc915b59a-300x137.jpg 300w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f6d30f elementor-widget elementor-widget-heading\" data-id=\"9f6d30f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nCaja de tamiz (cuerpo del marco vibratorio).<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aebb05 elementor-widget elementor-widget-text-editor\" data-id=\"5aebb05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La caja de cribado es la parte portante de la criba. Est\u00e1 fabricada con placa de acero Q235 de 8 mm de espesor. Su estructura se compone de placa lateral, soporte transversal, placa de refuerzo y viga transversal. Al estar soportada por la placa lateral, esta soporta el peso del material y de la caja, transmitiendo la fuerza de excitaci\u00f3n a sus distintas partes. Para reforzar la rigidez de la placa lateral, se utiliza acero de 12 canales en ambos lados como refuerzo. La viga transversal est\u00e1 soldada con acero de 12 canales doble y placa de refuerzo de 10 mm de espesor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-149ec7a elementor-widget elementor-widget-heading\" data-id=\"149ec7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nPantallas agitadoras:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e118cd5 elementor-widget elementor-widget-text-editor\" data-id=\"e118cd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El <span style=\"color: #008000;\"><a style=\"color: #008000;\" href=\"https:\/\/solidscontrolworld.com\/es\/pantallas-vibratorias\/\">pantalla vibratoria<\/a><\/span> Es una parte importante para la remoci\u00f3n de s\u00f3lidos y la recuperaci\u00f3n del fluido de perforaci\u00f3n. El tama\u00f1o de las part\u00edculas s\u00f3lidas que puede remover la zaranda vibratoria depende completamente del tama\u00f1o de la malla de la criba. La zaranda vibratoria utiliza una malla de criba de ranura en forma de cu\u00f1a de acero inoxidable, con una separaci\u00f3n de 0,6 mm, una dimensi\u00f3n externa de 1400 \u00d7 780 mm y una superficie de criba de 1,1 m\u00b2. Para garantizar la fiabilidad de la superficie de la criba, el m\u00e9todo de fijaci\u00f3n de la misma tambi\u00e9n influye considerablemente en la capacidad; este dise\u00f1o utiliza compresi\u00f3n con pernos. La superficie inferior de la caja de la criba est\u00e1 soldada con seis tubos de acero sin costura de \u03a648 \u00d7 4 mm y la placa de la criba est\u00e1 atornillada a ella, lo que cumple con los requisitos de resistencia y ahorra material. El asiento de la abrazadera del perno cuenta con una almohadilla de goma vulcanizada que evita el desgaste y dificulta que la criba se da\u00f1e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d8900 elementor-widget elementor-widget-heading\" data-id=\"f5d8900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caja de alimentaci\u00f3n de lodo:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e60f85 elementor-widget elementor-widget-text-editor\" data-id=\"3e60f85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La caja exterior est\u00e1 soldada con una placa de acero de 4 mm de espesor, y la parte interior del agua est\u00e1 procesada con una placa perforada de 2,5 mm de espesor, esta estructura tiene buena <span style=\"color: #008000;\"><a style=\"color: #008000;\" href=\"https:\/\/solidscontrolworld.com\/es\/tanque-de-lodo\/\">lodo<\/a> <\/span>efecto amortiguador y puede separar granos grandes de arena y escombros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b707936 elementor-widget elementor-widget-heading\" data-id=\"b707936\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dispositivo de potencia:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87bbcba elementor-widget elementor-widget-text-editor\" data-id=\"87bbcba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEl motor vibratorio es la fuente de energ\u00eda de la vibraci\u00f3n de la caja de cribado, que se utiliza para generar una fuerza de excitaci\u00f3n peri\u00f3dica, forzando a la caja de cribado apoyada en el resorte de amortiguaci\u00f3n a producir una vibraci\u00f3n peri\u00f3dica continua y tambi\u00e9n forzando a la <a title=\"Proveedor de agitadores de lutitas para fluidos de perforaci\u00f3n\">fluido de perforaci\u00f3n<\/a> La malla del tamiz vibra, de modo que las part\u00edculas s\u00f3lidas y el l\u00edquido, de tama\u00f1o inferior al de la malla, regresan al fluido de perforaci\u00f3n a trav\u00e9s de ella. Las part\u00edculas s\u00f3lidas que no pueden atravesar la malla se env\u00edan al extremo de descarga mediante las cribas vibratorias, logrando as\u00ed la separaci\u00f3n s\u00f3lido-l\u00edquido. La viga vibratoria de este dispositivo est\u00e1 compuesta por un motor de vibraci\u00f3n a prueba de explosiones de marca, con bajo nivel de ruido, funcionamiento suave, larga vida \u00fatil y f\u00e1cil instalaci\u00f3n y mantenimiento.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccb753f elementor-widget elementor-widget-heading\" data-id=\"ccb753f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dispositivo de amortiguaci\u00f3n de vibraciones:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5423a83 elementor-widget elementor-widget-text-editor\" data-id=\"5423a83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dispositivo de amortiguaci\u00f3n de vibraciones:<br \/>Utiliza 4 resortes de compresi\u00f3n espirales de alta resistencia, que ofrecen buena estabilidad, buen efecto de amortiguaci\u00f3n y bajo nivel de ruido. Los resortes de amortiguaci\u00f3n soportan la caja de cribado y el excitador, garantizando as\u00ed suficiente espacio para la vibraci\u00f3n de la caja de cribado, a la vez que ayudan a la caja de cribado a alcanzar la vibraci\u00f3n requerida, amortiguando y reduciendo la carga din\u00e1mica transmitida a la base y al tanque de fluido de perforaci\u00f3n.<br \/>Base:<br \/>La base est\u00e1 hecha \u00edntegramente de acero de 12 canales soldados para soportar las piezas anteriores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbe0224 elementor-widget elementor-widget-heading\" data-id=\"bbe0224\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principio de funcionamiento del agitador de esquisto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6c7141 elementor-widget elementor-widget-text-editor\" data-id=\"e6c7141\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El agitador de lutitas para fluido de perforaci\u00f3n se basa en la fuerza exc\u00e9ntrica del motor vibratorio, que a trav\u00e9s del haz de excitaci\u00f3n produce un movimiento lineal que impulsa el movimiento alternativo de toda la caja de la criba a lo largo del eje Y. Las part\u00edculas son expulsadas y retroceden bajo la vibraci\u00f3n de la superficie de la criba, de modo que el material avanza continuamente durante la vibraci\u00f3n de la superficie de la criba. La expulsi\u00f3n y ca\u00edda del material impactan en la superficie de la criba, lo que resulta en la separaci\u00f3n de part\u00edculas m\u00e1s peque\u00f1as que el orificio de la criba. Al mismo tiempo, el lodo en la superficie de la criba es lanzado hacia arriba a lo largo del eje Y y luego avanza cuando cae libremente, de modo que es lanzado constantemente hacia arriba y hacia abajo para hacer que el lodo avance. El lodo l\u00edquido se filtra en el charco de lodo a trav\u00e9s de la criba, mientras que las part\u00edculas s\u00f3lidas en el lodo que son m\u00e1s grandes que la malla de la criba se tamizan, desempe\u00f1ando as\u00ed un papel en la purificaci\u00f3n del lodo l\u00edquido.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85e479b elementor-widget elementor-widget-heading\" data-id=\"85e479b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dos par\u00e1metros importantes del agitador de esquisto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efe61f1 elementor-widget elementor-widget-text-editor\" data-id=\"efe61f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1.Velocidad de rotaci\u00f3n (RPM)<br \/>2. Amplitud (mm) Los dos factores se suman para obtener la fuerza de vibraci\u00f3n G, por ejemplo, 3,5 g significa que la fuerza de vibraci\u00f3n es 3,5 grados atr\u00e1s de aceleraci\u00f3n gravitacional.<br \/>La magnitud de la fuerza de vibraci\u00f3n determina el rendimiento de la m\u00e1quina de cribado (rendimiento, eficiencia de cribado).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bb1168 elementor-widget elementor-widget-heading\" data-id=\"2bb1168\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Proceso de cribado del fluido de perforaci\u00f3n de la zaranda vibratoria de lutitas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0abd619 elementor-widget elementor-widget-text-editor\" data-id=\"0abd619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante el proceso de perforaci\u00f3n, cuando el fluido de perforaci\u00f3n regresa a la boca del pozo a trav\u00e9s del pozo con las astillas de roca, ingresa al tanque de registro y al colector a trav\u00e9s del tanque elevado, y fluye hacia la zaranda vibratoria. La separaci\u00f3n s\u00f3lido-l\u00edquido es un proceso en el que el flujo inicial del fluido de perforaci\u00f3n hacia la zaranda vibratoria no se separa inmediatamente, sino que, mientras una peque\u00f1a parte de la zaranda se separa primero, la mayor parte de la fase l\u00edquida se separa inmediatamente a lo largo de la superficie de la zaranda, formando as\u00ed una capa de fluido de perforaci\u00f3n. Con el proceso de separaci\u00f3n, esta capa se vuelve cada vez m\u00e1s delgada, hasta que la fase l\u00edquida se detiene en un punto determinado de la superficie de la zaranda.<br \/>La ubicaci\u00f3n de la terminaci\u00f3n de la fase l\u00edquida se denomina generalmente l\u00ednea de terminaci\u00f3n de la fase l\u00edquida. Tras cruzar esta l\u00ednea, las part\u00edculas de la fase s\u00f3lida contin\u00faan avanzando hasta salir de la zaranda vibratoria. Cuando la zaranda vibratoria con fluido de perforaci\u00f3n funciona con normalidad, la l\u00ednea de terminaci\u00f3n de la fase l\u00edquida se encuentra entre 2\/3 y 3\/4 de la longitud efectiva de la \u00faltima criba, es decir, el fluido de perforaci\u00f3n se extiende sobre 2\/3 a 3\/4 de esta. El proceso de tamizado incluye la penetraci\u00f3n de la fase l\u00edquida y el movimiento de la fase s\u00f3lida en la criba. La fase s\u00f3lida es una masa de fragmentos de roca de forma y tama\u00f1o irregulares, mientras que el fluido de perforaci\u00f3n es un fluido con una variabilidad espec\u00edfica. Las part\u00edculas de la fase s\u00f3lida se sumergen en el fluido de perforaci\u00f3n y permanecen h\u00famedas, rodeadas por \u00e9l, tras la separaci\u00f3n. Por lo tanto, la estructura y los par\u00e1metros de la zaranda vibratoria y la malla de la criba, el rendimiento del fluido de perforaci\u00f3n y la instalaci\u00f3n de la criba vibratoria afectar\u00e1n directamente el proceso de tamizado y la eficacia de la zaranda vibratoria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2beae21 elementor-widget elementor-widget-heading\" data-id=\"2beae21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sugerencias para el uso en campo de la zaranda vibratoria de fluido de perforaci\u00f3n <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65194a8 elementor-widget elementor-widget-heading\" data-id=\"65194a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">De acuerdo con la condici\u00f3n del fragmento de roca del estrato, elija el agitador de lutitas adecuado.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b59a05f elementor-widget elementor-widget-text-editor\" data-id=\"b59a05f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para garantizar la correcta separaci\u00f3n s\u00f3lido-l\u00edquido del fluido de perforaci\u00f3n en la criba, las part\u00edculas deben proyectarse sobre su superficie para lograr un alto rendimiento y una alta tasa de descarga de viruta. Durante el proceso de proyecci\u00f3n, las part\u00edculas se transportan al puerto de descarga en forma de proyectil. Si el \u00edndice de proyecci\u00f3n es bajo, cuando las part\u00edculas s\u00f3lidas est\u00e1n sumergidas, la velocidad de transporte es demasiado lenta, lo que f\u00e1cilmente bloquear\u00e1 la criba y reducir\u00e1 la capacidad de procesamiento, e incluso provocar\u00e1 el deslizamiento de la pulpa y la p\u00e9rdida de fluido de perforaci\u00f3n. Al separar las part\u00edculas s\u00f3lidas, una velocidad de transporte demasiado lenta aumentar\u00e1 la probabilidad de que peque\u00f1as part\u00edculas penetren en la criba e incluso provocar\u00e1 su acumulaci\u00f3n, lo que provocar\u00e1 su destrucci\u00f3n prematura por sobrecarga. El \u00edndice de lanzamiento no debe ser demasiado grande, siempre que las part\u00edculas de la fase s\u00f3lida puedan superar la adhesi\u00f3n entre \u00e9l y el fluido de perforaci\u00f3n y separarse, demasiado grande aumentar\u00e1 la colisi\u00f3n de part\u00edculas que caen sobre la pantalla, lo que resultar\u00e1 en la probabilidad de que m\u00e1s part\u00edculas diminutas atraviesen la pantalla, pero tambi\u00e9n intensificar\u00e1 el desgaste de la pantalla, reducir\u00e1 la vida \u00fatil de la pantalla, pero tambi\u00e9n plantear\u00e1 requisitos m\u00e1s altos para la resistencia del agitador de pizarra.<br \/>Las condiciones estratigr\u00e1ficas var\u00edan considerablemente de una regi\u00f3n a otra, al igual que las caracter\u00edsticas de las lascas de roca, lo que genera numerosas diferencias en el rendimiento y los par\u00e1metros del fluido de perforaci\u00f3n. Al seleccionar una zaranda vibratoria, se deben considerar la amplitud de la criba vibratoria, el \u00edndice de penetraci\u00f3n, la trayectoria, el \u00e1ngulo de penetraci\u00f3n, la posici\u00f3n de instalaci\u00f3n del motor y del resorte, y la frecuencia de vibraci\u00f3n, seg\u00fan la situaci\u00f3n geogr\u00e1fica de las lascas de roca, el rendimiento del fluido de perforaci\u00f3n y los par\u00e1metros de perforaci\u00f3n para seleccionar la zaranda vibratoria m\u00e1s adecuada. En \u00e1reas con estratos complejos y grandes variaciones en la naturaleza de las lascas de roca, se puede considerar el uso de una zaranda vibratoria de doble v\u00eda lineal y el\u00edptica plana con conversi\u00f3n de frecuencia y fuerza de excitaci\u00f3n ajustable para seleccionar la frecuencia, la fuerza de excitaci\u00f3n, el \u00e1ngulo de penetraci\u00f3n y la trayectoria adecuados seg\u00fan la naturaleza de las lascas de roca en el estrato. Generalmente, en el caso de part\u00edculas de lascas de roca grandes y alta gravedad espec\u00edfica, la fuerza de excitaci\u00f3n es alta y la frecuencia de vibraci\u00f3n es baja; en el caso de part\u00edculas de lascas de roca peque\u00f1as y fr\u00e1giles, la fuerza de excitaci\u00f3n es baja y la frecuencia de vibraci\u00f3n es alta, y se seleccionan los par\u00e1metros adecuados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-849cf0a elementor-widget elementor-widget-heading\" data-id=\"849cf0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Seleccione la pantalla correcta <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ab7917 elementor-widget elementor-widget-text-editor\" data-id=\"8ab7917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSe recomienda utilizar una malla con alta resistencia a la magnetizaci\u00f3n y un tama\u00f1o de malla adecuado al rendimiento del fluido de perforaci\u00f3n durante su uso. Para formaciones de limolita y arena fluida propensas a obstruirse, utilice mallas desatascadoras.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda985e elementor-widget elementor-widget-heading\" data-id=\"fda985e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Instalaci\u00f3n correcta del agitador de pizarra<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7876081 elementor-widget elementor-widget-text-editor\" data-id=\"7876081\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La poca rigidez del soporte de la base y una fijaci\u00f3n poco confiable provocar\u00e1n una distorsi\u00f3n de la trayectoria durante el uso del agitador de pizarra, y la base del agitador de pizarra debe instalarse sobre una base r\u00edgida con buena rigidez y fijaci\u00f3n confiable durante la instalaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d12883 elementor-widget elementor-widget-heading\" data-id=\"9d12883\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ajuste adecuado del \u00e1ngulo de elevaci\u00f3n durante el uso.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-761eed2 elementor-widget elementor-widget-text-editor\" data-id=\"761eed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUn \u00e1ngulo de elevaci\u00f3n inadecuado de la caja de cribado provocar\u00e1 el escurrimiento de la pulpa y la acumulaci\u00f3n de arena. Durante el uso, el \u00e1ngulo de elevaci\u00f3n debe ajustarse seg\u00fan la posici\u00f3n de la l\u00ednea de terminaci\u00f3n de la fase l\u00edquida.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1a176b elementor-widget elementor-widget-heading\" data-id=\"b1a176b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ajuste de la fuerza de excitaci\u00f3n adecuada<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4938b71 elementor-widget elementor-widget-text-editor\" data-id=\"4938b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLos bloques exc\u00e9ntricos en ambos extremos del motor de excitaci\u00f3n se utilizan para ajustar la fuerza de excitaci\u00f3n del motor, y el porcentaje debe ajustarse de acuerdo con el rendimiento del fluido de perforaci\u00f3n y el caudal en el proceso, y el porcentaje de los bloques exc\u00e9ntricos de los dos motores de excitaci\u00f3n debe ser el mismo al ajustar, de lo contrario, la pantalla vibratoria no puede formar resonancia y afectar el efecto de procesamiento.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08fc7fe elementor-widget elementor-widget-heading\" data-id=\"08fc7fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mantenimiento adecuado<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b553ade elementor-widget elementor-widget-text-editor\" data-id=\"b553ade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Al realizar el mantenimiento del agitador de lutitas y reemplazar el resorte de amortiguaci\u00f3n, es necesario reemplazarlo por uno del mismo rendimiento y elasticidad. Est\u00e1 prohibido mezclar resortes nuevos y viejos. Al reemplazar el motor de excitaci\u00f3n, se debe reemplazar por uno del mismo modelo y rendimiento similar; de lo contrario, la vibraci\u00f3n del agitador de lutitas se ver\u00e1 afectada y su rendimiento se ver\u00e1 afectado.<br \/>Solidscontrolworld - Fabricante de pantallas vibratorias de pizarra de alta calidad tiene m\u00e1s de 13 a\u00f1os de experiencia en el campo de control de s\u00f3lidos de perforaci\u00f3n; podemos elegir el tipo de vibrador de pizarra adecuado para usted; el vibrador de pizarra rentable no lo defraudar\u00e1; puede confiar en nuestro servicio, cont\u00e1ctenos ahora!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf61a5c elementor-widget elementor-widget-text-editor\" data-id=\"bf61a5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">Las zarandas vibratorias est\u00e1n adaptadas para separar s\u00f3lidos grandes de fluidos en la perforaci\u00f3n y miner\u00eda. Constituyen la primera fase del tratamiento de s\u00f3lidos y lodos en la miner\u00eda y perforaci\u00f3n de petr\u00f3leo y gas. Reducen el contenido de s\u00f3lidos y facilitan otras etapas al proporcionar niveles m\u00e1s bajos de s\u00f3lidos a los equipos de control con fluidos de perforaci\u00f3n para optimizar las necesidades de tratamiento.\u00a0 \u00a0<\/span><\/span><\/p><p><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">Las zarandas vibratorias son equipos esenciales para el control de s\u00f3lidos en la limpieza y separaci\u00f3n de los recortes de perforaci\u00f3n. Son vitales para la limpieza de s\u00f3lidos, el tratamiento de lodos y la eliminaci\u00f3n de compuestos\/materiales extra\u00f1os.\u00a0\u00a0<\/span><\/span><\/p><p><strong><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">Caracter\u00edsticas principales de los agitadores de pizarra<\/span><\/span><\/strong><\/p><p><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">-Caja de tamiz\u00a0<\/span><\/span><\/p><p><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">-Pantallas vibratorias de esquisto\u00a0<\/span><\/span><\/p><p><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">-Caja de alimentaci\u00f3n de lodo\u00a0<\/span><\/span><\/p><p><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">-Dispositivo de potencia\u00a0<\/span><\/span><\/p><p><span style=\"color: #333333; font-family: Inter, inter;\"><span style=\"font-size: 16px;\">-Dispositivo de amortiguaci\u00f3n de vibraciones\u00a0<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1be3280 elementor-widget elementor-widget-html\" data-id=\"1be3280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table class=\"aligncenter\">\r\n<tbody>\r\n<tr class=\"thhh\">\r\n<th width=\"146\"><b>Modelo<\/b><\/th>\r\n<th width=\"174\"><b>ABZS 104<\/b><\/th>\r\n<th width=\"173\"><b>ABZS 103<\/b><\/th>\r\n<th width=\"187\"><b>ABZS 70-3P<\/b><\/th>\r\n<th width=\"188\"><b>ABZS 103K<\/b><\/th>\r\n<th width=\"188\"><b>ABZS 85-2P<\/b><\/th>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Capacidad<\/td>\r\n<td width=\"174\">\u2264 150 m3\/h (660 GPM)<\/td>\r\n<td width=\"173\">\u2264 120 m3\/h (528 GPM)<\/td>\r\n<td width=\"187\">\u2264 120 m3\/h (528 GPM)<\/td>\r\n<td width=\"188\">\u2264 120 m3\/h (528 GPM)<\/td>\r\n<td width=\"188\">\u2264 80 m3\/h (352 GPM)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Potencia nominal de los motores<\/td>\r\n<td width=\"174\">1.865kw (2.5hp) x2 (Mart\u00edn)<\/td>\r\n<td width=\"173\">1,5 kW (2,0 CV) x 2 (OLI)<\/td>\r\n<td width=\"187\">1,72 kW (2,3 CV) x 2 (OLI)<\/td>\r\n<td width=\"188\">1,5 kw (2,0 caballos de fuerza) x2 (OLI)<\/td>\r\n<td width=\"188\">1,0 kw (1,3 5 CV) x2 (OLI)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Fuerza de salida<\/td>\r\n<td width=\"174\">\u2264 8,5 G<\/td>\r\n<td width=\"173\">\u2264 8,0 Gs<\/td>\r\n<td width=\"187\">\u2264 7,5 G<\/td>\r\n<td width=\"188\">\u2264 8,0 Gs<\/td>\r\n<td width=\"188\">\u2264 7,0 Gs<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Temperatura de funcionamiento<\/td>\r\n<td width=\"174\">30 \u00b0C (86 \u00b0F)<\/td>\r\n<td width=\"173\">30 \u00b0C (86 \u00b0F)<\/td>\r\n<td width=\"187\">30 \u00b0C (86 \u00b0F)<\/td>\r\n<td width=\"188\">30 \u00b0C (86 \u00b0F)<\/td>\r\n<td width=\"188\">30 \u00b0C (86 \u00b0F)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Gama de dise\u00f1os<\/td>\r\n<td width=\"174\">- 40 - 50 \u00b0C (- 40 - 122 \u00b0F)<\/td>\r\n<td width=\"173\">- 40 - 50 \u00b0C (- 40 - 122 \u00b0F)<\/td>\r\n<td width=\"187\">- 40 - 50 \u00b0C (- 40 - 122 \u00b0F)<\/td>\r\n<td width=\"188\">- 40 - 50 \u00b0C (- 40 - 122 \u00b0F)<\/td>\r\n<td width=\"188\">- 40 - 50 \u00b0C (- 40 - 122 \u00b0F)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Fecha de ruido<\/td>\r\n<td width=\"174\">7 5 - 8 5 d\u00edas BA<\/td>\r\n<td width=\"173\">7 5 - 8 5 d\u00edas BA<\/td>\r\n<td width=\"187\">7 5 - 8 5 d\u00edas BA<\/td>\r\n<td width=\"188\">7 5 - 8 5 d\u00edas BA<\/td>\r\n<td width=\"188\">7 5 - 8 5 d\u00edas BA<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Ajuste de la cubierta<\/td>\r\n<td width=\"174\">- 1\u00b0~ + 5\u00b0<\/td>\r\n<td width=\"173\">- 1\u00b0~ + 5\u00b0<\/td>\r\n<td width=\"187\">- 1\u00b0~ + 5\u00b0<\/td>\r\n<td width=\"188\">- 1\u00b0~ + 5\u00b0<\/td>\r\n<td width=\"188\">- 1\u00b0~ + 3\u00b0<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Material de la pantalla<\/td>\r\n<td width=\"174\">Marco compuesto \/ Marco de metal<\/td>\r\n<td width=\"173\">Marco de metal compuesto<\/td>\r\n<td width=\"187\">Marco de metal<\/td>\r\n<td width=\"188\">Acero inoxidable\/poliuretano<\/td>\r\n<td width=\"188\">Marco de metal<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Tama\u00f1o de la pantalla<\/td>\r\n<td width=\"174\">5 8 5 x 1 1 6 5 mm<\/td>\r\n<td width=\"173\">5 8 5 x 1 1 6 5 mm<\/td>\r\n<td width=\"187\">700x1250 mm<\/td>\r\n<td width=\"188\">5 8 5 x 1 1 6 5 mm<\/td>\r\n<td width=\"188\">8 5 0 x 1 2 5 0 mm<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Cantidad de pantalla<\/td>\r\n<td width=\"174\">4 piezas<\/td>\r\n<td width=\"173\">3 piezas<\/td>\r\n<td width=\"187\">3 piezas<\/td>\r\n<td width=\"188\">3 piezas<\/td>\r\n<td width=\"188\">2 piezas<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">\u00c1rea de filtrado<\/td>\r\n<td width=\"174\">2,73 m\u00b2 (3,0 pies\u00b2)<\/td>\r\n<td width=\"173\">2,1 m\u00b2 (2,35 pies\u00b2)<\/td>\r\n<td width=\"187\">2,63 m\u00b2 (29,2 pies\u00b2)<\/td>\r\n<td width=\"188\">2,1 m\u00b2 (29,2 pies\u00b2)<\/td>\r\n<td width=\"188\">2,1 m\u00b2 (2,35 pies\u00b2)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Peso<\/td>\r\n<td width=\"174\">1 4 8 0 kg s<\/td>\r\n<td width=\"173\">1 3 2 0 kg s<\/td>\r\n<td width=\"187\">1 4 0 0 kg s<\/td>\r\n<td width=\"188\">1 3 9 5 kg s<\/td>\r\n<td width=\"188\">1 2 5 0 kg s<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Dimensi\u00f3n<\/td>\r\n<td width=\"174\">2 9 5 0 x1 6 9 0 x1 4 2 0<\/td>\r\n<td width=\"173\">2 3 7 0 X1 6 9 0 X1 4 2 0<\/td>\r\n<td width=\"187\">2 8 7 0 x1 7 7 2 x1 4 0 0<\/td>\r\n<td width=\"188\">2 3 7 0 x1 6 9 0 x1 4 2 0<\/td>\r\n<td width=\"188\">2 4 4 0 x1 7 7 2 x1 4 0 0<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Voltaje<\/td>\r\n<td colspan=\"5\" width=\"909\">220-240 V\/50 Hz, 380-415 V\/50 Hz, 440-480 V\/60 Hz, 575-600 V\/60 Hz<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\">Aprobaci\u00f3n<\/td>\r\n<td colspan=\"5\" width=\"909\">UL\/ ATEX\/ BV\/ IADC\/ J AS - ANZ ISO 9001:2015 \/ CE<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"146\"><\/td>\r\n<td style=\"text-align: left;\" colspan=\"5\" width=\"909\">Condiciones de prueba para estos par\u00e1metros: Densidad del lodo: 1,2 g\/cm3, Viscosidad del lodo: 45 s, Malla: 40<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8522c27\" data-id=\"8522c27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc7debd elementor-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bc7debd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-location-arrow\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Habitaci\u00f3n 1924, Bloque D, Plaza Wanda, ciudad de Tangshan, China.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-business-time\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lunes a viernes: 8:00-17:30<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ebd0c41 elementor-share-buttons--view-icon elementor-share-buttons--skin-minimal elementor-share-buttons--shape-rounded elementor-share-buttons--align-left elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"4ebd0c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_facebook\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en facebook\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_twitter\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en Twitter\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_linkedin\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartir en linkedin\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; Shale Shaker Drilling fluid shale shaker is the most used solid control equipment in the process of oil drilling mud treatment. Contact Download Brochure Category:\u00a0Solids Control Contact info@solidscontrolworld.com +8613784677772 86-315-7651760 DESCRIPTION Definition of drilling fluid shale shaker Drilling fluid shale shaker is the most used solid control [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Steel Frame Shaker Screen Manufacturer | Solids Control World","_seopress_titles_desc":"Shale shakers are used to separate sand from oil or gas. They are often used in fracking operations. Buy high quality shale shakers online. Visit now!","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-3420","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Drilling Fluid Shale Shaker Supplier | Solids Control World<\/title>\n<meta name=\"description\" content=\"Shop high-quality mud shaker screens for effective solids control in drilling operations. Enhance performance and efficiency with reliable screening solutions today.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidscontrolworld.com\/es\/agitador-de-esquisto\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drilling Fluid Shale Shaker Supplier | Solids Control World\" \/>\n<meta property=\"og:description\" content=\"Shop high-quality mud shaker screens for effective solids control in drilling operations. Enhance performance and efficiency with reliable screening solutions today.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidscontrolworld.com\/es\/agitador-de-esquisto\/\" \/>\n<meta property=\"og:site_name\" content=\"Solids Control World\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-25T06:04:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proveedor de zarandas vibratorias para fluidos de perforaci\u00f3n | Solids Control World","description":"Compre mallas de alta calidad para zarandeadores de lodo para un control eficaz de s\u00f3lidos en operaciones de perforaci\u00f3n. Mejore el rendimiento y la eficiencia con soluciones de cribado confiables hoy mismo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidscontrolworld.com\/es\/agitador-de-esquisto\/","og_locale":"es_MX","og_type":"article","og_title":"Drilling Fluid Shale Shaker Supplier | Solids Control World","og_description":"Shop high-quality mud shaker screens for effective solids control in drilling operations. Enhance performance and efficiency with reliable screening solutions today.","og_url":"https:\/\/solidscontrolworld.com\/es\/agitador-de-esquisto\/","og_site_name":"Solids Control World","article_modified_time":"2024-10-25T06:04:01+00:00","og_image":[{"url":"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solidscontrolworld.com\/shale-shaker\/","url":"https:\/\/solidscontrolworld.com\/shale-shaker\/","name":"Proveedor de zarandas vibratorias para fluidos de perforaci\u00f3n | Solids Control World","isPartOf":{"@id":"https:\/\/solidscontrolworld.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solidscontrolworld.com\/shale-shaker\/#primaryimage"},"image":{"@id":"https:\/\/solidscontrolworld.com\/shale-shaker\/#primaryimage"},"thumbnailUrl":"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6.jpg","datePublished":"2021-06-05T06:28:06+00:00","dateModified":"2024-10-25T06:04:01+00:00","description":"Compre mallas de alta calidad para zarandeadores de lodo para un control eficaz de s\u00f3lidos en operaciones de perforaci\u00f3n. Mejore el rendimiento y la eficiencia con soluciones de cribado confiables hoy mismo.","breadcrumb":{"@id":"https:\/\/solidscontrolworld.com\/shale-shaker\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidscontrolworld.com\/shale-shaker\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/solidscontrolworld.com\/shale-shaker\/#primaryimage","url":"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6.jpg","contentUrl":"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/edc04f8107c4c039d1625fb9e9a6ac6.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/solidscontrolworld.com\/shale-shaker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solidscontrolworld.com\/"},{"@type":"ListItem","position":2,"name":"Shale shaker"}]},{"@type":"WebSite","@id":"https:\/\/solidscontrolworld.com\/#website","url":"https:\/\/solidscontrolworld.com\/","name":"Mundo de control de s\u00f3lidos","description":"","publisher":{"@id":"https:\/\/solidscontrolworld.com\/#\/schema\/person\/2c126362537c0f0e6d4a8dfba9fc68b0"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidscontrolworld.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/solidscontrolworld.com\/#\/schema\/person\/2c126362537c0f0e6d4a8dfba9fc68b0","name":"mundodecontroldes\u00f3lidos","logo":{"@id":"https:\/\/solidscontrolworld.com\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/solidscontrolworld.com"]}]}},"_links":{"self":[{"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/pages\/3420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/comments?post=3420"}],"version-history":[{"count":9,"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/pages\/3420\/revisions"}],"predecessor-version":[{"id":11725,"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/pages\/3420\/revisions\/11725"}],"wp:attachment":[{"href":"https:\/\/solidscontrolworld.com\/es\/wp-json\/wp\/v2\/media?parent=3420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}