{"id":3234,"date":"2021-05-31T16:21:20","date_gmt":"2021-05-31T16:21:20","guid":{"rendered":"https:\/\/solidscontrolworld.com\/?page_id=3234"},"modified":"2025-11-18T08:08:48","modified_gmt":"2025-11-18T08:08:48","slug":"bomba-centrifuga","status":"publish","type":"page","link":"https:\/\/solidscontrolworld.com\/pt\/centrifugal-pump\/","title":{"rendered":"Bomba centr\u00edfuga"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3234\" class=\"elementor elementor-3234\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-26120281 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"26120281\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78766b58\" data-id=\"78766b58\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-470a641c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"470a641c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-13d34d6c\" data-id=\"13d34d6c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18879752 elementor-widget elementor-widget-image\" data-id=\"18879752\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"472\" height=\"303\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d.jpg\" class=\"attachment-full size-full wp-image-9552\" alt=\"bomba centr\u00edfuga\" srcset=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d.jpg 472w, https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d-300x193.jpg 300w, https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d-470x303.jpg 470w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da14f3d elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"da14f3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 \u0645\u0646 3\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"da14f3d\" data-elementor-lightbox-title=\"Centrifugal Pump10\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTExNjQsInVybCI6Imh0dHBzOlwvXC9zb2xpZHNjb250cm9sd29ybGQuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8xMFwvQ2VudHJpZnVnYWwtUHVtcDEwLnBuZyIsInNsaWRlc2hvdyI6ImRhMTRmM2QifQ%3D%3D\" href=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/10\/Centrifugal-Pump10.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/10\/Centrifugal-Pump10-150x150.png\" alt=\"Bomba Centr\u00edfuga 10\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 \u0645\u0646 3\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"da14f3d\" data-elementor-lightbox-title=\"Centrifugal Pump11\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTExNjcsInVybCI6Imh0dHBzOlwvXC9zb2xpZHNjb250cm9sd29ybGQuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8xMFwvQ2VudHJpZnVnYWwtUHVtcDExLnBuZyIsInNsaWRlc2hvdyI6ImRhMTRmM2QifQ%3D%3D\" href=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/10\/Centrifugal-Pump11.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/10\/Centrifugal-Pump11-150x150.png\" alt=\"Bomba Centr\u00edfuga 11\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 \u0645\u0646 3\" data-no-translation-aria-label=\"\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"da14f3d\" data-elementor-lightbox-title=\"Centrifugal Pump1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTExNjUsInVybCI6Imh0dHBzOlwvXC9zb2xpZHNjb250cm9sd29ybGQuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8xMFwvQ2VudHJpZnVnYWwtUHVtcDEucG5nIiwic2xpZGVzaG93IjoiZGExNGYzZCJ9\" href=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/10\/Centrifugal-Pump1.png\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2024\/10\/Centrifugal-Pump1-150x150.png\" alt=\"Bomba centr\u00edfuga 1\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3500822a\" data-id=\"3500822a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ccfaeb6 elementor-widget elementor-widget-heading\" data-id=\"7ccfaeb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bomba centr\u00edfuga<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34debbaf elementor-widget elementor-widget-text-editor\" data-id=\"34debbaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>As bombas centr\u00edfugas s\u00e3o usadas para transportar fluidos atrav\u00e9s da convers\u00e3o da energia cin\u00e9tica rotacional em energia hidrodin\u00e2mica do fluxo do fluido. A energia rotacional normalmente prov\u00e9m de um motor a combust\u00e3o ou el\u00e9trico. Elas s\u00e3o uma subclasse de turbom\u00e1quinas din\u00e2micas axissim\u00e9tricas de absor\u00e7\u00e3o de trabalho.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a7b1ddd elementor-widget elementor-widget-text-editor\" data-id=\"2a7b1ddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCategoria:\u00a0<a href=\"https:\/\/solidscontrolworld.com\/pt\/equipamentos-de-controle-de-solidos\/\" rel=\"tag\">Controle de S\u00f3lidos<\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-173003d8\" data-id=\"173003d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7aeedd47 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7aeedd47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope-open\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@solidscontrolworld.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-volume\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+8613784677772<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-fax\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">86-315-7651760<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fc422e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fc422e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-27d3f83e\" data-id=\"27d3f83e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4ce966 elementor-widget elementor-widget-text-editor\" data-id=\"b4ce966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f25161 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f25161\" data-element_type=\"section\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-row\"><div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6999059\" data-id=\"6999059\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-element-b6046b0 elementor-widget elementor-widget-text-editor\" data-id=\"b6046b0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-text-editor elementor-clearfix\"><p><span style=\"color: #000000;\"><span title=\"pe\u00e7as de bomba centr\u00edfuga\">Bombas centr\u00edfugas<\/span>\u00a0S\u00e3o usados para transportar fluidos pela convers\u00e3o de energia cin\u00e9tica rotacional em energia hidrodin\u00e2mica do fluxo do fluido. A energia rotacional normalmente prov\u00e9m de um motor ou motor el\u00e9trico. S\u00e3o uma subclasse de trabalho din\u00e2mico axim\u00e9trico-absorvente.<\/span><\/p><p><span style=\"color: #000000;\">Bombas de \u00e1gua centr\u00edfugas ou bombas de lama centr\u00edfugas s\u00e3o um componente crucial do processo de limpeza de lama. S\u00e3o essencialmente bombas rotodin\u00e2micas usadas para criar fluxo energizando a lama. Possuem um selo mec\u00e2nico de liga met\u00e1lica dura de alto desgaste para evitar qualquer vazamento iminente durante a vida \u00fatil. A lama entra no\u00a0<span title=\"pe\u00e7as de bomba centr\u00edfuga\">bomba centr\u00edfuga<\/span>\u00a0atrav\u00e9s do impulsor e ent\u00e3o acelera. O fluido ent\u00e3o flui radialmente para fora, em dire\u00e7\u00e3o ao componente difusor da bomba. Geralmente tem\u00a0<span title=\"pe\u00e7as de bomba centr\u00edfuga\">bomba mais espessa<\/span>\u00a0casos com fluxo mais razo\u00e1vel. O fluido tratado \u00e9 ent\u00e3o descarregado pela tubula\u00e7\u00e3o a jusante do equipamento.\u00a0<\/span><\/p><p><span style=\"color: #000000;\">Bombas centr\u00edfugas s\u00e3o amplamente utilizadas no tratamento de lama de constru\u00e7\u00e3o, mas tamb\u00e9m existem outras aplica\u00e7\u00f5es. Bombas centr\u00edfugas tamb\u00e9m s\u00e3o amplamente utilizadas no tratamento de \u00e1guas residuais e na ind\u00fastria de petr\u00f3leo e g\u00e1s. Equipamentos utilizados no processo de limpeza de lama \u2013 desintegradores e desassoreadores. Al\u00e9m disso, tamb\u00e9m servem como bombas cin\u00e9ticas para misturadores de lama a jato.<\/span><\/p><p><span style=\"color: #000000;\"><strong>Principais caracter\u00edsticas das bombas centr\u00edfugas<\/strong><\/span><\/p><ul><li><span style=\"color: #000000;\">Impulsores<\/span><\/li><li><span style=\"color: #000000;\">Manga do eixo<\/span><\/li><li><span style=\"color: #000000;\">Skid de bomba de fundi\u00e7\u00e3o<\/span><\/li><li><span style=\"color: #000000;\">Equipamentos de separa\u00e7\u00e3o e transporte<\/span><\/li><li><span style=\"color: #000000;\"><span style=\"color: #000000;\">Uma unidade de energia<\/span><\/span><\/li><\/ul><p><span style=\"color: #000000;\"><strong>Nossas vantagens:<\/strong><\/span><\/p><p><strong><span style=\"color: #000000; font-family: Poppins; font-size: 0.9rem;\">Gama completa de modelos Acess\u00f3rios intercambi\u00e1veis Entrega r\u00e1pida<\/span><\/strong><\/p><p><span style=\"color: #000000;\">O corpo da bomba e o impulsor s\u00e3o feitos de ferro fundido de liga resistente ao desgaste<\/span><\/p><p><span style=\"color: #000000;\">O impulsor adota estrutura aberta ou fechada para transportar meio fluido de alta viscosidade<\/span><\/p><p><span style=\"color: #000000;\">Superf\u00edcie curva suave do canal de fluxo do corpo da bomba, alta efici\u00eancia de trabalho<\/span><\/p><p><span style=\"color: #000000;\">O mecanismo de veda\u00e7\u00e3o dupla garante uma opera\u00e7\u00e3o est\u00e1vel a longo prazo da bomba centr\u00edfuga<\/span><\/p><p><span style=\"color: #000000;\">Todos os acess\u00f3rios da bomba centr\u00edfuga s\u00e3o totalmente intercambi\u00e1veis com as bombas centr\u00edfugas Mison e Western<\/span><\/p><p><span style=\"color: #000000;\">Pode ser usado como bomba de fornecimento de polpa para equipamentos de separa\u00e7\u00e3o s\u00f3lido-l\u00edquido<\/span><\/p><p><span style=\"color: #000000;\">Tamb\u00e9m pode ser usada como uma bomba de mistura de lama para mistura de lama a jato<\/span><\/p><p><span style=\"color: #000000;\">Assim como <span title=\"Bomba centr\u00edfuga\">bombas de enchimento<\/span> para bombas de reabastecimento e bombas de polpa, etc.<\/span><\/p><p><strong><span style=\"color: #000000;\">Dur\u00e1vel<\/span><\/strong><\/p><p><span style=\"color: #000000;\">A parte de transbordamento adota ferro fundido de liga resistente ao desgaste,<\/span><\/p><p><span style=\"color: #000000;\">Caminho de fluxo suave, desempenho superior,<\/span><\/p><p><span style=\"color: #000000;\">Adequado para ambientes de lama e dur\u00e1vel.<\/span><\/p><p><strong><span style=\"color: #000000;\">Vida longa<\/span><\/strong><\/p><p><span style=\"color: #000000;\">Selo para estrutura de selo duplo (selo mec\u00e2nico, selo de embalagem)<\/span><\/p><p><span style=\"color: #000000;\">Desempenho est\u00e1vel e confi\u00e1vel, excelente qualidade,<\/span><\/p><p><span style=\"color: #000000;\">Instala\u00e7\u00e3o e manuten\u00e7\u00e3o f\u00e1ceis e r\u00e1pidas.<\/span><\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-271aa19 elementor-widget elementor-widget-html\" data-id=\"271aa19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<table class=\"aligncenter\">\r\n<tbody>\r\n<tr class=\"thhh\">\r\n<td rowspan=\"2\" width=\"210\"><strong>\u00a0<\/strong>\r\n\r\nModelo<\/td>\r\n<td width=\"104\">Di\u00e2metro do impulsor<\/td>\r\n<td width=\"103\">Fluxo<\/td>\r\n<td width=\"104\">Elevador<\/td>\r\n<td width=\"104\">Velocidade de rota\u00e7\u00e3o<\/td>\r\n<td width=\"116\">Efici\u00eancia<\/td>\r\n<td width=\"103\">NPSH<\/td>\r\n<td width=\"104\">Pot\u00eancia de sa\u00edda<\/td>\r\n<td width=\"106\">Pot\u00eancia de entrada<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"104\">(polegada)<\/td>\r\n<td width=\"103\">(m\u00b3\/h)<\/td>\r\n<td width=\"104\">(m)<\/td>\r\n<td width=\"104\">(rpm)<\/td>\r\n<td width=\"116\">(%)<\/td>\r\n<td width=\"103\">(m)<\/td>\r\n<td width=\"104\">(KW)<\/td>\r\n<td width=\"106\">(KW)<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB10 x8 x14 J<\/td>\r\n<td width=\"104\">14<\/td>\r\n<td width=\"103\">410<\/td>\r\n<td width=\"104\">33<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">57<\/td>\r\n<td width=\"103\">4<\/td>\r\n<td width=\"104\">64 .6<\/td>\r\n<td width=\"106\">110<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB10 x8 x14 J<\/td>\r\n<td width=\"104\">13<\/td>\r\n<td width=\"103\">380<\/td>\r\n<td width=\"104\">26<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">56<\/td>\r\n<td width=\"103\">4<\/td>\r\n<td width=\"104\">48<\/td>\r\n<td width=\"106\">90<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB10 x8 x14 J<\/td>\r\n<td width=\"104\">12<\/td>\r\n<td width=\"103\">370<\/td>\r\n<td width=\"104\">18<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">52<\/td>\r\n<td width=\"103\">4<\/td>\r\n<td width=\"104\">34 .9<\/td>\r\n<td width=\"106\">75<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB8 x6 x14 J<\/td>\r\n<td width=\"104\">13 .5<\/td>\r\n<td width=\"103\">265<\/td>\r\n<td width=\"104\">40<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">66<\/td>\r\n<td width=\"103\">2 .5<\/td>\r\n<td width=\"104\">43 .7<\/td>\r\n<td width=\"106\">90<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB8 x6 x14 J<\/td>\r\n<td width=\"104\">12 .5<\/td>\r\n<td width=\"103\">255<\/td>\r\n<td width=\"104\">32<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">67<\/td>\r\n<td width=\"103\">2 .5<\/td>\r\n<td width=\"104\">33 .2<\/td>\r\n<td width=\"106\">75<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB8 x6 x14 J<\/td>\r\n<td width=\"104\">11 .5<\/td>\r\n<td width=\"103\">250<\/td>\r\n<td width=\"104\">24<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">63<\/td>\r\n<td width=\"103\">2 .7<\/td>\r\n<td width=\"104\">25 .9<\/td>\r\n<td width=\"106\">55<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB8 x6 x14 J<\/td>\r\n<td width=\"104\">11<\/td>\r\n<td width=\"103\">245<\/td>\r\n<td width=\"104\">20<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">62<\/td>\r\n<td width=\"103\">2 .7<\/td>\r\n<td width=\"104\">21 .5<\/td>\r\n<td width=\"106\">45<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB8 x6 x11 J<\/td>\r\n<td width=\"104\">11<\/td>\r\n<td width=\"103\">220<\/td>\r\n<td width=\"104\">23<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">65<\/td>\r\n<td width=\"103\">3<\/td>\r\n<td width=\"104\">21 .2<\/td>\r\n<td width=\"106\">45<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB8 x6 x11 J<\/td>\r\n<td width=\"104\">10<\/td>\r\n<td width=\"103\">210<\/td>\r\n<td width=\"104\">17<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">70<\/td>\r\n<td width=\"103\">3<\/td>\r\n<td width=\"104\">13 .9<\/td>\r\n<td width=\"106\">30<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB6 x5 x14 J<\/td>\r\n<td width=\"104\">12 .5<\/td>\r\n<td width=\"103\">200<\/td>\r\n<td width=\"104\">34<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">65<\/td>\r\n<td width=\"103\">3 .2<\/td>\r\n<td width=\"104\">28 .5<\/td>\r\n<td width=\"106\">55<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB6 x5 x14 J<\/td>\r\n<td width=\"104\">12<\/td>\r\n<td width=\"103\">195<\/td>\r\n<td width=\"104\">31<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">68<\/td>\r\n<td width=\"103\">3<\/td>\r\n<td width=\"104\">24 .2<\/td>\r\n<td width=\"106\">45<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB6 x5 x14 J<\/td>\r\n<td width=\"104\">11<\/td>\r\n<td width=\"103\">190<\/td>\r\n<td width=\"104\">24<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">70<\/td>\r\n<td width=\"103\">3 .5<\/td>\r\n<td width=\"104\">17 .7<\/td>\r\n<td width=\"106\">37<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB6 x5 x11 J<\/td>\r\n<td width=\"104\">11<\/td>\r\n<td width=\"103\">190<\/td>\r\n<td width=\"104\">23<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">70<\/td>\r\n<td width=\"103\">3<\/td>\r\n<td width=\"104\">17<\/td>\r\n<td width=\"106\">37<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB5 x4 x14 J<\/td>\r\n<td width=\"104\">12<\/td>\r\n<td width=\"103\">110<\/td>\r\n<td width=\"104\">32<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">65<\/td>\r\n<td width=\"103\">3 .5<\/td>\r\n<td width=\"104\">14 .7<\/td>\r\n<td width=\"106\">30<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB5 x4 x14 J<\/td>\r\n<td width=\"104\">11<\/td>\r\n<td width=\"103\">105<\/td>\r\n<td width=\"104\">27<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">68<\/td>\r\n<td width=\"103\">4<\/td>\r\n<td width=\"104\">11 .4<\/td>\r\n<td width=\"106\">22<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB5 x4 x14 J<\/td>\r\n<td width=\"104\">10<\/td>\r\n<td width=\"103\">100<\/td>\r\n<td width=\"104\">21<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">68<\/td>\r\n<td width=\"103\">4 .2<\/td>\r\n<td width=\"104\">8 .4<\/td>\r\n<td width=\"106\">18 .5<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB5 x4 x14 J<\/td>\r\n<td width=\"104\">9 .5<\/td>\r\n<td width=\"103\">95<\/td>\r\n<td width=\"104\">17<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">68<\/td>\r\n<td width=\"103\">4 .2<\/td>\r\n<td width=\"104\">6 .5<\/td>\r\n<td width=\"106\">15<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB4 x3 x13 J<\/td>\r\n<td width=\"104\">11 .5<\/td>\r\n<td width=\"103\">90<\/td>\r\n<td width=\"104\">30<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">65<\/td>\r\n<td width=\"103\">3 .6<\/td>\r\n<td width=\"104\">11 .3<\/td>\r\n<td width=\"106\">22<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB4 x3 x13 J<\/td>\r\n<td width=\"104\">11<\/td>\r\n<td width=\"103\">85<\/td>\r\n<td width=\"104\">27<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">65<\/td>\r\n<td width=\"103\">3 .5<\/td>\r\n<td width=\"104\">9 .6<\/td>\r\n<td width=\"106\">18 .5<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB4 x3 x13 J<\/td>\r\n<td width=\"104\">10<\/td>\r\n<td width=\"103\">80<\/td>\r\n<td width=\"104\">21<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">66<\/td>\r\n<td width=\"103\">3 .5<\/td>\r\n<td width=\"104\">6 .9<\/td>\r\n<td width=\"106\">15<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB4 x3 x13 J<\/td>\r\n<td width=\"104\">9<\/td>\r\n<td width=\"103\">70<\/td>\r\n<td width=\"104\">16<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">66<\/td>\r\n<td width=\"103\">3 .5<\/td>\r\n<td width=\"104\">4 .6<\/td>\r\n<td width=\"106\">11<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB3 x2 x13 J<\/td>\r\n<td width=\"104\">11 .5<\/td>\r\n<td width=\"103\">60<\/td>\r\n<td width=\"104\">27<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">56<\/td>\r\n<td width=\"103\">2 .5<\/td>\r\n<td width=\"104\">7 .8<\/td>\r\n<td width=\"106\">15<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB3 x2 x13 J<\/td>\r\n<td width=\"104\">11<\/td>\r\n<td width=\"103\">50<\/td>\r\n<td width=\"104\">25<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">56<\/td>\r\n<td width=\"103\">2 .5<\/td>\r\n<td width=\"104\">6 .1<\/td>\r\n<td width=\"106\">11<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB3 x2 x13 J<\/td>\r\n<td width=\"104\">10<\/td>\r\n<td width=\"103\">45<\/td>\r\n<td width=\"104\">21<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">60<\/td>\r\n<td width=\"103\">2 .3<\/td>\r\n<td width=\"104\">4 .3<\/td>\r\n<td width=\"106\">7 .5<\/td>\r\n<\/tr>\r\n<tr>\r\n<td width=\"210\">ABSB3 x2 x10 J<\/td>\r\n<td width=\"104\">9<\/td>\r\n<td width=\"103\">40<\/td>\r\n<td width=\"104\">16<\/td>\r\n<td width=\"104\">1450<\/td>\r\n<td width=\"116\">60<\/td>\r\n<td width=\"103\">2 .1<\/td>\r\n<td width=\"104\">2 .9<\/td>\r\n<td width=\"106\">5 .5<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7acbb033\" data-id=\"7acbb033\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f620992 elementor-align-end elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1f620992\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-location-arrow\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sala 1924, Bloco D, Pra\u00e7a Wanda, cidade de Tangshan, China.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-business-time\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Seg-Sex: 8:00-17:30<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f2aa elementor-share-buttons--view-icon elementor-share-buttons--skin-minimal elementor-share-buttons--shape-rounded elementor-share-buttons--align-left elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"5f2aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_facebook\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartilhe no Facebook\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_twitter\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartilhe no Twitter\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t\t<div\n\t\t\t\t\t\t\tclass=\"elementor-share-btn elementor-share-btn_linkedin\"\n\t\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\t\ttabindex=\"0\"\n\t\t\t\t\t\t\taria-label=\"Compartilhe no LinkedIn\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Centrifugal Pump Centrifugal pumps are used to transport fluids by the conversion of rotational kinetic energy to the hydrodynamic energy of the fluid flow. The rotational energy typically comes from an engine or electric motor. They are a sub-class of dynamic axisymmetric work-absorbing turbomachinery Category:\u00a0Solids Control info@solidscontrolworld.com +8613784677772 86-315-7651760 Centrifugal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-3234","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centrifugal Pump | Centrifugal Pump Basics | Solids control world<\/title>\n<meta name=\"description\" content=\"Solids Control World explains centrifugal pump basics, types, and features, providing reliable solutions for construction, oil, gas, wastewater, and slurry handling.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solidscontrolworld.com\/pt\/bomba-centrifuga\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centrifugal Pump | Centrifugal Pump Basics | Solids control world\" \/>\n<meta property=\"og:description\" content=\"Solids Control World explains centrifugal pump basics, types, and features, providing reliable solutions for construction, oil, gas, wastewater, and slurry handling.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solidscontrolworld.com\/pt\/bomba-centrifuga\/\" \/>\n<meta property=\"og:site_name\" content=\"Solids Control World\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T08:08:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"472\" \/>\n\t<meta property=\"og:image:height\" content=\"303\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bomba Centr\u00edfuga | No\u00e7\u00f5es B\u00e1sicas sobre Bombas Centr\u00edfugas | Mundo do Controle de S\u00f3lidos","description":"A Solids Control World explica os princ\u00edpios b\u00e1sicos, os tipos e os recursos das bombas centr\u00edfugas, fornecendo solu\u00e7\u00f5es confi\u00e1veis para constru\u00e7\u00e3o, petr\u00f3leo, g\u00e1s, \u00e1guas residuais e manuseio de chorume.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solidscontrolworld.com\/pt\/bomba-centrifuga\/","og_locale":"pt_BR","og_type":"article","og_title":"Centrifugal Pump | Centrifugal Pump Basics | Solids control world","og_description":"Solids Control World explains centrifugal pump basics, types, and features, providing reliable solutions for construction, oil, gas, wastewater, and slurry handling.","og_url":"https:\/\/solidscontrolworld.com\/pt\/bomba-centrifuga\/","og_site_name":"Solids Control World","article_modified_time":"2025-11-18T08:08:48+00:00","og_image":[{"width":472,"height":303,"url":"https:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solidscontrolworld.com\/centrifugal-pump\/","url":"https:\/\/solidscontrolworld.com\/centrifugal-pump\/","name":"Bomba Centr\u00edfuga | No\u00e7\u00f5es B\u00e1sicas sobre Bombas Centr\u00edfugas | Mundo do Controle de S\u00f3lidos","isPartOf":{"@id":"https:\/\/solidscontrolworld.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solidscontrolworld.com\/centrifugal-pump\/#primaryimage"},"image":{"@id":"https:\/\/solidscontrolworld.com\/centrifugal-pump\/#primaryimage"},"thumbnailUrl":"http:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d.jpg","datePublished":"2021-05-31T16:21:20+00:00","dateModified":"2025-11-18T08:08:48+00:00","description":"A Solids Control World explica os princ\u00edpios b\u00e1sicos, os tipos e os recursos das bombas centr\u00edfugas, fornecendo solu\u00e7\u00f5es confi\u00e1veis para constru\u00e7\u00e3o, petr\u00f3leo, g\u00e1s, \u00e1guas residuais e manuseio de chorume.","breadcrumb":{"@id":"https:\/\/solidscontrolworld.com\/centrifugal-pump\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solidscontrolworld.com\/centrifugal-pump\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/solidscontrolworld.com\/centrifugal-pump\/#primaryimage","url":"http:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d.jpg","contentUrl":"http:\/\/solidscontrolworld.com\/wp-content\/uploads\/2023\/07\/f9a541ce537a0254a35c1c1c7f90c7d.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/solidscontrolworld.com\/centrifugal-pump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solidscontrolworld.com\/"},{"@type":"ListItem","position":2,"name":"Centrifugal pump"}]},{"@type":"WebSite","@id":"https:\/\/solidscontrolworld.com\/#website","url":"https:\/\/solidscontrolworld.com\/","name":"Mundo de controle de s\u00f3lidos","description":"","publisher":{"@id":"https:\/\/solidscontrolworld.com\/#\/schema\/person\/2c126362537c0f0e6d4a8dfba9fc68b0"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solidscontrolworld.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/solidscontrolworld.com\/#\/schema\/person\/2c126362537c0f0e6d4a8dfba9fc68b0","name":"mundo de controle de s\u00f3lidos","logo":{"@id":"https:\/\/solidscontrolworld.com\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/solidscontrolworld.com"]}]}},"_links":{"self":[{"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/pages\/3234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/comments?post=3234"}],"version-history":[{"count":39,"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/pages\/3234\/revisions"}],"predecessor-version":[{"id":12387,"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/pages\/3234\/revisions\/12387"}],"wp:attachment":[{"href":"https:\/\/solidscontrolworld.com\/pt\/wp-json\/wp\/v2\/media?parent=3234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}